{"id":256,"count":21,"description":"","link":"https:\/\/www.112carlotagalgos.com\/es\/tag\/adoption-es\/","name":"adoption","slug":"adoption-es","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>adoption Archives - 112carlotagalgos.com | A sanctuary for the galgos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.112carlotagalgos.com\/es\/tag\/adoption-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"adoption Archives - 112carlotagalgos.com | A sanctuary for the galgos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.112carlotagalgos.com\/es\/tag\/adoption-es\/\" \/>\n<meta property=\"og:site_name\" content=\"112carlotagalgos.com | A sanctuary for the galgos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@112carlotagalgo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.112carlotagalgos.com\\\/es\\\/tag\\\/adoption-es\\\/\",\"url\":\"https:\\\/\\\/www.112carlotagalgos.com\\\/es\\\/tag\\\/adoption-es\\\/\",\"name\":\"adoption Archives - 112carlotagalgos.com | A sanctuary for the galgos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.112carlotagalgos.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.112carlotagalgos.com\\\/es\\\/tag\\\/adoption-es\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.112carlotagalgos.com\\\/es\\\/tag\\\/adoption-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.112carlotagalgos.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"adoption\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.112carlotagalgos.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.112carlotagalgos.com\\\/es\\\/\",\"name\":\"112carlotagalgos.com | A sanctuary for the galgos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.112carlotagalgos.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.112carlotagalgos.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.112carlotagalgos.com\\\/es\\\/#organization\",\"name\":\"112 Carlota Galgos\",\"url\":\"https:\\\/\\\/www.112carlotagalgos.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.112carlotagalgos.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.112carlotagalgos.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/112-carlota-galgos-logo-b.png\",\"contentUrl\":\"https:\\\/\\\/www.112carlotagalgos.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/112-carlota-galgos-logo-b.png\",\"width\":216,\"height\":112,\"caption\":\"112 Carlota Galgos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.112carlotagalgos.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/112-Carlota-Galgos-148387698542171\\\/\",\"https:\\\/\\\/x.com\\\/112carlotagalgo\",\"https:\\\/\\\/www.instagram.com\\\/112carlotagalgos\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCBM7d5aKYrFe_nE2UBtxFPQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"adoption Archives - 112carlotagalgos.com | A sanctuary for the galgos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.112carlotagalgos.com\/es\/tag\/adoption-es\/","og_locale":"es_ES","og_type":"article","og_title":"adoption Archives - 112carlotagalgos.com | A sanctuary for the galgos","og_url":"https:\/\/www.112carlotagalgos.com\/es\/tag\/adoption-es\/","og_site_name":"112carlotagalgos.com | A sanctuary for the galgos","twitter_card":"summary_large_image","twitter_site":"@112carlotagalgo","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.112carlotagalgos.com\/es\/tag\/adoption-es\/","url":"https:\/\/www.112carlotagalgos.com\/es\/tag\/adoption-es\/","name":"adoption Archives - 112carlotagalgos.com | A sanctuary for the galgos","isPartOf":{"@id":"https:\/\/www.112carlotagalgos.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.112carlotagalgos.com\/es\/tag\/adoption-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.112carlotagalgos.com\/es\/tag\/adoption-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.112carlotagalgos.com\/es\/"},{"@type":"ListItem","position":2,"name":"adoption"}]},{"@type":"WebSite","@id":"https:\/\/www.112carlotagalgos.com\/es\/#website","url":"https:\/\/www.112carlotagalgos.com\/es\/","name":"112carlotagalgos.com | A sanctuary for the galgos","description":"","publisher":{"@id":"https:\/\/www.112carlotagalgos.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.112carlotagalgos.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.112carlotagalgos.com\/es\/#organization","name":"112 Carlota Galgos","url":"https:\/\/www.112carlotagalgos.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.112carlotagalgos.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.112carlotagalgos.com\/wp-content\/uploads\/2021\/04\/112-carlota-galgos-logo-b.png","contentUrl":"https:\/\/www.112carlotagalgos.com\/wp-content\/uploads\/2021\/04\/112-carlota-galgos-logo-b.png","width":216,"height":112,"caption":"112 Carlota Galgos"},"image":{"@id":"https:\/\/www.112carlotagalgos.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/112-Carlota-Galgos-148387698542171\/","https:\/\/x.com\/112carlotagalgo","https:\/\/www.instagram.com\/112carlotagalgos\/","https:\/\/www.youtube.com\/channel\/UCBM7d5aKYrFe_nE2UBtxFPQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.112carlotagalgos.com\/es\/wp-json\/wp\/v2\/tags\/256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.112carlotagalgos.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.112carlotagalgos.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.112carlotagalgos.com\/es\/wp-json\/wp\/v2\/posts?tags=256"},{"href":"https:\/\/www.112carlotagalgos.com\/es\/wp-json\/wp\/v2\/portfolio?tags=256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}